{"id":15970,"date":"2025-03-17T13:58:44","date_gmt":"2025-03-17T12:58:44","guid":{"rendered":"https:\/\/unitedprint.com\/easyprint-launch\/"},"modified":"2025-03-25T09:54:04","modified_gmt":"2025-03-25T08:54:04","slug":"easyprint-launch","status":"publish","type":"post","link":"https:\/\/unitedprint.com\/it\/easyprint-launch\/","title":{"rendered":"Easyprint Launch"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.16&#8243; max_width=&#8221;1400px&#8221; module_alignment=&#8221;center&#8221; custom_margin=&#8221;0px||0px|&#8221; custom_padding=&#8221;0px||0px|&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row module_class=&#8221; et_pb_row_fullwidth&#8221; _builder_version=&#8221;4.16.0&#8243; width=&#8221;100%&#8221; width_tablet=&#8221;100%&#8221; width_phone=&#8221;100%&#8221; width_last_edited=&#8221;off|desktop&#8221; max_width=&#8221;100%&#8221; max_width_tablet=&#8221;100%&#8221; max_width_phone=&#8221;100%&#8221; max_width_last_edited=&#8221;off|desktop&#8221; module_alignment=&#8221;center&#8221; custom_padding=&#8221;0px||0px|&#8221; make_fullwidth=&#8221;on&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_image src=&#8221;https:\/\/unitedprint.com\/wp-content\/uploads\/2025\/03\/Header.jpg&#8221; title_text=&#8221;Header&#8221; url=&#8221;http:\/\/easyprint.com&#8221; force_fullwidth=&#8221;on&#8221; align_tablet=&#8221;center&#8221; align_phone=&#8221;center&#8221; align_last_edited=&#8221;on|desktop&#8221; admin_label=&#8221;Headerbild&#8221; _builder_version=&#8221;4.16.0&#8243; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; custom_padding_last_edited=&#8221;on|desktop&#8221; _builder_version=&#8221;4.16.0&#8243; max_width=&#8221;1400px&#8221; module_alignment=&#8221;center&#8221; custom_margin=&#8221;||||false|false&#8221; custom_padding=&#8221;20px||0px||false|false&#8221; custom_padding_tablet=&#8221;20px|||&#8221; custom_padding_phone=&#8221;&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row custom_padding_last_edited=&#8221;on|desktop&#8221; _builder_version=&#8221;4.16.0&#8243; custom_padding=&#8221;20px||0px|&#8221; custom_padding_tablet=&#8221;&#8221; custom_padding_phone=&#8221;&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_blurb image=&#8221;https:\/\/unitedprint.com\/wordpress\/wp-content\/uploads\/2018\/07\/up-unitedprint-se-icon-2.svg&#8221; icon_placement=&#8221;left&#8221; image_icon_width=&#8221;40px&#8221; content_max_width=&#8221;100%&#8221; admin_label=&#8221;Headline&#8221; _builder_version=&#8221;4.16.0&#8243; header_level=&#8221;h1&#8243; body_font=&#8221;|||on|||||&#8221; animation=&#8221;off&#8221; image_max_width=&#8221;40px&#8221; saved_tabs=&#8221;all&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h1>Easyprint<\/h1>\n<p>[\/et_pb_blurb][\/et_pb_column][\/et_pb_row][et_pb_row custom_padding_last_edited=&#8221;on|desktop&#8221; _builder_version=&#8221;4.16.0&#8243; custom_padding=&#8221;15px||0px|&#8221; custom_padding_tablet=&#8221;&#8221; custom_padding_phone=&#8221;&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_text admin_label=&#8221;Datum + Ort&#8221; _builder_version=&#8221;4.16.0&#8243; custom_margin=&#8221;0px||0px|&#8221; custom_padding=&#8221;0px||0px|&#8221; global_colors_info=&#8221;{}&#8221;]17 marzo 2025<br \/>\n<span data-sheets-root=\"1\">RADEBEUL, Germania<\/span>[\/et_pb_text][et_pb_text admin_label=&#8221;Titel&#8221; _builder_version=&#8221;4.16.0&#8243; custom_margin=&#8221;-8px||0px|&#8221; custom_padding=&#8221;0px||0px|&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h2><span data-sheets-root=\"1\">Easyprint: Finalmente carta da copia sostenibile ed economica<\/span><\/h2>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row custom_padding_last_edited=&#8221;on|desktop&#8221; _builder_version=&#8221;4.16.0&#8243; custom_padding=&#8221;||||false|false&#8221; custom_padding_tablet=&#8221;&#8221; custom_padding_phone=&#8221;&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_text admin_label=&#8221;Intro&#8221; _builder_version=&#8221;4.16.0&#8243; global_colors_info=&#8221;{}&#8221;]<\/p>\n<div class=\"page\" title=\"Page 1\">\n<div class=\"section\">\n<div class=\"layoutArea\">\n<div class=\"column\">\n<div class=\"page\" title=\"Page 1\">\n<div class=\"section\">\n<div class=\"layoutArea\">\n<div class=\"page\" title=\"Page 1\">\n<div class=\"section\">\n<div class=\"layoutArea\">\n<div class=\"column\">\n<div class=\"column\">\n<p class=\"p1\"><em>Unitedprint SE, l&#8217;azienda dietro i marchi di successo a livello europeo print24, Infowerk e USS, amplia il suo portafoglio con il marchio di carta \u201cEasyprint Carta da Stampa \/ Carta da Copia\u201d e il nuovo portale specializzato in carta da stampa \u201cEasyprint\u201d.<\/em><\/p>\n<p>&nbsp;<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.16.0&#8243; global_colors_info=&#8221;{}&#8221;]<\/p>\n<div class=\"page\" title=\"Page 1\">\n<div class=\"section\">\n<div class=\"layoutArea\">\n<div class=\"column\">\n<div class=\"page\" title=\"Page 1\">\n<div class=\"section\">\n<div class=\"layoutArea\">\n<div class=\"page\" title=\"Page 1\">\n<div class=\"section\">\n<div class=\"layoutArea\">\n<div class=\"column\">\n<div class=\"column\">\n<p class=\"p1\"><span data-sheets-root=\"1\">Accanto alla moltitudine di carte da copia sempre uguali, mancano alternative moderne, sostenibili e allo stesso tempo economiche. Unitedprint, nota per le sue offerte innovative di Web-To-Print e programmi di acquisto, offre con \u201cEasyprint Carta da Stampa \/ Carta da Copia\u201d la soluzione ideale. I clienti beneficiano di prezzi online vantaggiosi, filiere certificate PEFC e della massima qualit\u00e0 dei materiali. Le diverse quantit\u00e0, da 500 fino a 140.000 fogli, confezionate in pratici pacchi da 500 fogli ciascuno, la rendono una scelta eccellente per uso privato e aziendale.<\/span><\/p>\n<p><span data-sheets-root=\"1\"><strong>Prezzo pi\u00f9 basso:<\/strong> Grazie a processi di produzione e catene di fornitura efficienti, Unitedprint \u00e8 in grado di offrire la carta da stampa \/ carta da copia a marchio Easyprint a prezzi nettamente inferiori rispetto ai consueti standard di mercato.<\/span><\/p>\n<p><span data-sheets-root=\"1\"><strong>Qualit\u00e0 superiore:<\/strong> La carta da stampa \/ carta da copia a marchio Easyprint garantisce risultati di stampa brillanti, \u00e8 resistente e perfettamente compatibile con tutte le stampanti e fotocopiatrici pi\u00f9 comuni. Rispetto ad altri prodotti, la \u201cCarta da Stampa \/ Carta da Copia Easyprint\u201d si distingue per il suo spessore superiore e l&#8217;eccezionale grado di bianco (CIE 160).<\/span><\/p>\n<p><span data-sheets-root=\"1\"><strong>Certificato ambientale:<\/strong> La \u201cCarta da Stampa \/ Carta da Copia Easyprint\u201d \u00e8 realizzata con legno proveniente da foreste gestite in modo sostenibile e certificata PEFC. L&#8217;intero processo di produzione e fornitura \u00e8 progettato per ottimizzare l&#8217;uso delle risorse e ridurre al minimo l&#8217;impatto ambientale.<\/span><\/p>\n<p><span data-sheets-root=\"1\">Con \u201cCarta da Stampa \/ Carta da Copia print24\u201d e \u201cCarta da Stampa \/ Carta da Copia Infowerk\u201d, Unitedprint si \u00e8 gi\u00e0 affermata come produttore esperto e crea un&#8217;esperienza utente ottimizzata con il portale di carta da stampa \u201cEasyprint\u201d. Grazie alla funzionalit\u00e0 innovativa dell&#8217;abbonamento, i clienti risparmiano fino al 10% sull&#8217;acquisto della \u201cCarta da Stampa \/ Carta da Copia Easyprint\u201d e ricevono regolarmente rifornimenti per il loro consumabile pi\u00f9 importante in ufficio.<\/span><\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row custom_padding_last_edited=&#8221;on|tablet&#8221; _builder_version=&#8221;4.16.0&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;|auto||auto|false|false&#8221; custom_margin_tablet=&#8221;-20px||-20px||false|false&#8221; custom_margin_phone=&#8221;0px||0px||false|false&#8221; custom_margin_last_edited=&#8221;on|tablet&#8221; custom_padding=&#8221;||||true|false&#8221; custom_padding_tablet=&#8221;10px||10px||true|false&#8221; custom_padding_phone=&#8221;0px||0px||true|false&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_divider show_divider_tablet=&#8221;on&#8221; show_divider_phone=&#8221;off&#8221; show_divider_last_edited=&#8221;on|desktop&#8221; _builder_version=&#8221;4.16.0&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;||-45px||false|false&#8221; custom_padding=&#8221;||0px||false|false&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_divider][\/et_pb_column][\/et_pb_row][et_pb_row custom_padding_last_edited=&#8221;on|desktop&#8221; _builder_version=&#8221;4.16.0&#8243; custom_padding=&#8221;||||false|false&#8221; custom_padding_tablet=&#8221;&#8221; custom_padding_phone=&#8221;&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_text admin_label=&#8221;Zitat&#8221; _builder_version=&#8221;4.16.0&#8243; global_colors_info=&#8221;{}&#8221;]<\/p>\n<div class=\"page\" title=\"Page 1\">\n<div class=\"section\">\n<div class=\"layoutArea\">\n<div class=\"column\">\n<div class=\"page\" title=\"Page 1\">\n<div class=\"section\">\n<div class=\"layoutArea\">\n<div class=\"page\" title=\"Page 1\">\n<div class=\"section\">\n<div class=\"layoutArea\">\n<div class=\"column\">\n<div class=\"column\">\n<p><span data-sheets-root=\"1\"><em>\u201cLa nostra \u2018Carta da Stampa \/ Carta da Copia Easyprint\u2019 \u00e8 l&#8217;evoluzione naturale nel mercato della carta da copia. Perch\u00e9 la carta da copia certificata ambientalmente e di alta qualit\u00e0 non dovrebbe essere anche conveniente? \u2018Carta da Stampa \/ Carta da Copia Easyprint\u2019 unisce tutti i punti di forza e con Easyprint.com abbiamo creato una piattaforma di vendita specializzata e incentrata sul cliente per tutti.\u201d<\/em><br \/><strong>Fabian Frenzel, CEO di Unitedprint.com SE.<\/strong><br \/><\/span><\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row custom_padding_last_edited=&#8221;on|tablet&#8221; _builder_version=&#8221;4.16.0&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;|auto||auto|false|false&#8221; custom_margin_tablet=&#8221;-20px||-20px||false|false&#8221; custom_margin_phone=&#8221;0px||0px||false|false&#8221; custom_margin_last_edited=&#8221;on|tablet&#8221; custom_padding=&#8221;||||true|false&#8221; custom_padding_tablet=&#8221;10px||10px||true|false&#8221; custom_padding_phone=&#8221;0px||0px||true|false&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_divider show_divider_tablet=&#8221;on&#8221; show_divider_phone=&#8221;off&#8221; show_divider_last_edited=&#8221;on|desktop&#8221; _builder_version=&#8221;4.16.0&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;||-45px||false|false&#8221; custom_padding=&#8221;||0px||false|false&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_divider][\/et_pb_column][\/et_pb_row][et_pb_row custom_padding_last_edited=&#8221;on|desktop&#8221; _builder_version=&#8221;4.16.0&#8243; custom_padding=&#8221;||||false|false&#8221; custom_padding_tablet=&#8221;&#8221; custom_padding_phone=&#8221;&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_text _builder_version=&#8221;4.16.0&#8243; global_colors_info=&#8221;{}&#8221;]<span data-sheets-root=\"1\">Carta da Stampa \/ Carta da Copia Easyprint\u201d \u00e8 ora disponibile per tutti gli interessati su <a href=\"http:\/\/easyprint.com\">easyprint.com<\/a>. I nuovi clienti risparmiano temporaneamente un ulteriore 10% con il codice sconto \u201cPCP\u201d per un acquisto unico.<\/span>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8221;4.16.0&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;||40px||false|false&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text admin_label=&#8221;Boilerplate&#8221; _builder_version=&#8221;4.16.0&#8243; _module_preset=&#8221;default&#8221; min_height=&#8221;65.2px&#8221; global_colors_info=&#8221;{}&#8221;]<span data-sheets-root=\"1\">Unitedprint.com SE \u00e8 un&#8217;azienda tecnologica innovativa che opera a livello globale nel settore del design, marketing, stampa e publishing. Come una delle principali aziende mondiali nella comunicazione visiva, Unitedprint gestisce i portali online Easyprint, Infowerk, print24 e il programma partner USS (Unitedprint Shop Services) in oltre 30 sedi nel mondo. Il marchio Infowerk Materials offre un accesso competitivo e conforme al mercato ai materiali di consumo per l&#8217;industria della stampa e dell&#8217;imballaggio in tutta Europa, tra cui carte grafiche, cartone e lastre da stampa..<\/span>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; disabled_on=&#8221;off|off|off&#8221; _builder_version=&#8221;4.16.0&#8243; background_color=&#8221;#006eb9&#8243; min_height=&#8221;98px&#8221; custom_margin=&#8221;||0px||false|false&#8221; custom_padding=&#8221;20px||20px|&#8221; custom_css_main_element=&#8221;padding-bottom: 0px !important;||margin-bottom: 0px !important;&#8221; locked=&#8221;off&#8221; collapsed=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row _builder_version=&#8221;4.16.0&#8243; background_size=&#8221;initial&#8221; background_position=&#8221;top_left&#8221; background_repeat=&#8221;repeat&#8221; module_alignment=&#8221;center&#8221; custom_margin=&#8221;0px||0px|&#8221; custom_padding=&#8221;20px||0px||false|false&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_text _builder_version=&#8221;4.16.0&#8243; text_orientation=&#8221;center&#8221; module_alignment=&#8221;center&#8221; custom_margin=&#8221;0px||0px|&#8221; custom_padding=&#8221;0px||0px|&#8221; hover_enabled=&#8221;0&#8243; global_colors_info=&#8221;{}&#8221; sticky_enabled=&#8221;0&#8243;]<a href=\"\/it\/infowerk2\/\"><img style=\"height: 20px; margin: 0 31px 10px 0;\" src=\"\/wordpress\/wp-content\/uploads\/2025\/03\/IW-Logo-1000x500-1.png\" alt=\"\" \/><\/a><a href=\"\/it\/print24\/\"><img style=\"height: 25px; margin: 0 32px 10px 0;\" src=\"\/wordpress\/wp-content\/uploads\/2018\/07\/print24-logo-weiss.svg\" alt=\"\" border=\"0\" \/><\/a><a href=\"\/it\/easyprint\/\"><img style=\"height: 22px; margin: 0 31px 10px 0;\" src=\"\/wordpress\/wp-content\/uploads\/2025\/03\/Easyprint-Logo_Easyprint-Logo-1.png\" alt=\"\" \/><\/a><a href=\"\/it\/unitedprint-shop-services\/\"><img style=\"height: 25px; margin: 0 0 10px 0;\" src=\"\/wordpress\/wp-content\/uploads\/2018\/10\/unitedprint-shop-service-logo-weiss.svg\" alt=\"\" \/><\/a>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Easyprint17 marzo 2025 RADEBEUL, GermaniaEasyprint: Finalmente carta da copia sostenibile ed economica Unitedprint SE, l&#8217;azienda dietro i marchi di successo a livello europeo print24, Infowerk e USS, amplia il suo portafoglio con il marchio di carta \u201cEasyprint Carta da Stampa \/ Carta da Copia\u201d e il nuovo portale specializzato in carta da stampa \u201cEasyprint\u201d. &nbsp; [&hellip;]<\/p>\n","protected":false},"author":22,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","_expiration-date-status":"","_expiration-date":0,"_expiration-date-type":"","_expiration-date-categories":[],"_expiration-date-options":[]},"categories":[105,51],"tags":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/unitedprint.com\/it\/wp-json\/wp\/v2\/posts\/15970"}],"collection":[{"href":"https:\/\/unitedprint.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/unitedprint.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/unitedprint.com\/it\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/unitedprint.com\/it\/wp-json\/wp\/v2\/comments?post=15970"}],"version-history":[{"count":5,"href":"https:\/\/unitedprint.com\/it\/wp-json\/wp\/v2\/posts\/15970\/revisions"}],"predecessor-version":[{"id":16204,"href":"https:\/\/unitedprint.com\/it\/wp-json\/wp\/v2\/posts\/15970\/revisions\/16204"}],"wp:attachment":[{"href":"https:\/\/unitedprint.com\/it\/wp-json\/wp\/v2\/media?parent=15970"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/unitedprint.com\/it\/wp-json\/wp\/v2\/categories?post=15970"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/unitedprint.com\/it\/wp-json\/wp\/v2\/tags?post=15970"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}